{"id":808,"date":"2015-02-02T17:01:15","date_gmt":"2015-02-02T16:01:15","guid":{"rendered":"http:\/\/febu.de\/?p=808"},"modified":"2022-08-12T09:13:02","modified_gmt":"2022-08-12T08:13:02","slug":"50-jahre-febu","status":"publish","type":"post","link":"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/","title":{"rendered":"50 Jahre FEBU"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/febu.de\/wp-content\/uploads\/50-jahre-febu-stanzteile-kunststoffspritzguss.jpg\" alt=\"50-jahre-febu-stanzteile-kunststoffspritzguss\" class=\"alignnone\" \/><\/p>\n<p>Am 02. Februar wurde FEBU 50 Jahre alt. Wir sind stolz, dass sich Qualit\u00e4t und Flexibilit\u00e4t durchgesetzt haben! Wir danken unseren Kunden, unseren Mitarbeitern sowie unseren Partnern f\u00fcr 50 spannende Jahre und freuen uns auf die weitere Zusammenarbeit mit Ihnen.<\/p>\n<p>Seit 1965 ist eine Menge passiert &#8211; machen Sie sich selbst ein Bild:<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 02. Februar wurde FEBU 50 Jahre alt. Wir sind stolz, dass sich Qualit\u00e4t und Flexibilit\u00e4t durchgesetzt haben! Wir danken unseren Kunden, unseren Mitarbeitern sowie unseren Partnern f\u00fcr 50 spannende Jahre und freuen uns auf die weitere Zusammenarbeit mit Ihnen. Seit 1965 ist eine Menge passiert &#8211; machen Sie sich selbst ein Bild:<\/p>\n","protected":false},"author":4,"featured_media":819,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neuigkeiten"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Am 02. Februar wurde FEBU 50 Jahre alt. Wir sind stolz, dass sich Qualit\u00e4t und Flexibilit\u00e4t durchgesetzt haben! Wir danken unseren Kunden, unseren Mitarbeitern sowie unseren Partnern f\u00fcr 50 spannende Jahre und freuen uns auf die weitere Zusammenarbeit mit Ihnen. Seit 1965 ist eine Menge passiert - machen Sie sich selbst ein Bild:\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"muensmedia\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"FEBU PUNCHING &amp; PLASTIC TECHNOLOGY -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"50 Jahre FEBU - FEBU PUNCHING &amp; PLASTIC TECHNOLOGY\" \/>\n\t\t<meta property=\"og:description\" content=\"Am 02. Februar wurde FEBU 50 Jahre alt. Wir sind stolz, dass sich Qualit\u00e4t und Flexibilit\u00e4t durchgesetzt haben! Wir danken unseren Kunden, unseren Mitarbeitern sowie unseren Partnern f\u00fcr 50 spannende Jahre und freuen uns auf die weitere Zusammenarbeit mit Ihnen. Seit 1965 ist eine Menge passiert - machen Sie sich selbst ein Bild:\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-02-02T16:01:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-08-12T08:13:02+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"50 Jahre FEBU - FEBU PUNCHING &amp; PLASTIC TECHNOLOGY\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Am 02. Februar wurde FEBU 50 Jahre alt. Wir sind stolz, dass sich Qualit\u00e4t und Flexibilit\u00e4t durchgesetzt haben! Wir danken unseren Kunden, unseren Mitarbeitern sowie unseren Partnern f\u00fcr 50 spannende Jahre und freuen uns auf die weitere Zusammenarbeit mit Ihnen. Seit 1965 ist eine Menge passiert - machen Sie sich selbst ein Bild:\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/2015\\\/02\\\/50-jahre-febu\\\/#blogposting\",\"name\":\"50 Jahre FEBU - FEBU PUNCHING & PLASTIC TECHNOLOGY\",\"headline\":\"50 Jahre FEBU\",\"author\":{\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/author\\\/muensmedia\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/febu.de\\\/wp-content\\\/uploads\\\/50-jahre-febu-stanzteile-kunststoffspritzguss.jpg\",\"width\":694,\"height\":162},\"datePublished\":\"2015-02-02T17:01:15+01:00\",\"dateModified\":\"2022-08-12T09:13:02+01:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/2015\\\/02\\\/50-jahre-febu\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/2015\\\/02\\\/50-jahre-febu\\\/#webpage\"},\"articleSection\":\"News, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/2015\\\/02\\\/50-jahre-febu\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/febu.de\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/febu.de\\\/category\\\/neuigkeiten\\\/#listItem\",\"name\":\"News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/febu.de\\\/category\\\/neuigkeiten\\\/#listItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/febu.de\\\/category\\\/neuigkeiten\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/2015\\\/02\\\/50-jahre-febu\\\/#listItem\",\"name\":\"50 Jahre FEBU\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/2015\\\/02\\\/50-jahre-febu\\\/#listItem\",\"position\":3,\"name\":\"50 Jahre FEBU\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/febu.de\\\/category\\\/neuigkeiten\\\/#listItem\",\"name\":\"News\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/#organization\",\"name\":\"FEBU STANZ- & KUNSTSTOFFTECHNIK\",\"url\":\"https:\\\/\\\/febu.de\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/author\\\/muensmedia\\\/#author\",\"url\":\"https:\\\/\\\/febu.de\\\/en\\\/author\\\/muensmedia\\\/\",\"name\":\"muensmedia\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/2015\\\/02\\\/50-jahre-febu\\\/#webpage\",\"url\":\"https:\\\/\\\/febu.de\\\/en\\\/2015\\\/02\\\/50-jahre-febu\\\/\",\"name\":\"50 Jahre FEBU - FEBU PUNCHING & PLASTIC TECHNOLOGY\",\"description\":\"Am 02. Februar wurde FEBU 50 Jahre alt. Wir sind stolz, dass sich Qualit\\u00e4t und Flexibilit\\u00e4t durchgesetzt haben! Wir danken unseren Kunden, unseren Mitarbeitern sowie unseren Partnern f\\u00fcr 50 spannende Jahre und freuen uns auf die weitere Zusammenarbeit mit Ihnen. Seit 1965 ist eine Menge passiert - machen Sie sich selbst ein Bild:\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/2015\\\/02\\\/50-jahre-febu\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/author\\\/muensmedia\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/author\\\/muensmedia\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/febu.de\\\/wp-content\\\/uploads\\\/50-jahre-febu-stanzteile-kunststoffspritzguss.jpg\",\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/2015\\\/02\\\/50-jahre-febu\\\/#mainImage\",\"width\":694,\"height\":162},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/2015\\\/02\\\/50-jahre-febu\\\/#mainImage\"},\"datePublished\":\"2015-02-02T17:01:15+01:00\",\"dateModified\":\"2022-08-12T09:13:02+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/febu.de\\\/en\\\/\",\"name\":\"FEBU STANZ- & KUNSTSTOFFTECHNIK\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/febu.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"50 Jahre FEBU - FEBU PUNCHING & PLASTIC TECHNOLOGY","description":"Am 02. Februar wurde FEBU 50 Jahre alt. Wir sind stolz, dass sich Qualit\u00e4t und Flexibilit\u00e4t durchgesetzt haben! Wir danken unseren Kunden, unseren Mitarbeitern sowie unseren Partnern f\u00fcr 50 spannende Jahre und freuen uns auf die weitere Zusammenarbeit mit Ihnen. Seit 1965 ist eine Menge passiert - machen Sie sich selbst ein Bild:","canonical_url":"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/#blogposting","name":"50 Jahre FEBU - FEBU PUNCHING & PLASTIC TECHNOLOGY","headline":"50 Jahre FEBU","author":{"@id":"https:\/\/febu.de\/en\/author\/muensmedia\/#author"},"publisher":{"@id":"https:\/\/febu.de\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/febu.de\/wp-content\/uploads\/50-jahre-febu-stanzteile-kunststoffspritzguss.jpg","width":694,"height":162},"datePublished":"2015-02-02T17:01:15+01:00","dateModified":"2022-08-12T09:13:02+01:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/#webpage"},"isPartOf":{"@id":"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/#webpage"},"articleSection":"News, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/febu.de\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/febu.de\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/febu.de\/category\/neuigkeiten\/#listItem","name":"News"}},{"@type":"ListItem","@id":"https:\/\/febu.de\/category\/neuigkeiten\/#listItem","position":2,"name":"News","item":"https:\/\/febu.de\/category\/neuigkeiten\/","nextItem":{"@type":"ListItem","@id":"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/#listItem","name":"50 Jahre FEBU"},"previousItem":{"@type":"ListItem","@id":"https:\/\/febu.de\/en\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/#listItem","position":3,"name":"50 Jahre FEBU","previousItem":{"@type":"ListItem","@id":"https:\/\/febu.de\/category\/neuigkeiten\/#listItem","name":"News"}}]},{"@type":"Organization","@id":"https:\/\/febu.de\/en\/#organization","name":"FEBU STANZ- & KUNSTSTOFFTECHNIK","url":"https:\/\/febu.de\/en\/"},{"@type":"Person","@id":"https:\/\/febu.de\/en\/author\/muensmedia\/#author","url":"https:\/\/febu.de\/en\/author\/muensmedia\/","name":"muensmedia"},{"@type":"WebPage","@id":"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/#webpage","url":"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/","name":"50 Jahre FEBU - FEBU PUNCHING & PLASTIC TECHNOLOGY","description":"Am 02. Februar wurde FEBU 50 Jahre alt. Wir sind stolz, dass sich Qualit\u00e4t und Flexibilit\u00e4t durchgesetzt haben! Wir danken unseren Kunden, unseren Mitarbeitern sowie unseren Partnern f\u00fcr 50 spannende Jahre und freuen uns auf die weitere Zusammenarbeit mit Ihnen. Seit 1965 ist eine Menge passiert - machen Sie sich selbst ein Bild:","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/febu.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/#breadcrumblist"},"author":{"@id":"https:\/\/febu.de\/en\/author\/muensmedia\/#author"},"creator":{"@id":"https:\/\/febu.de\/en\/author\/muensmedia\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/febu.de\/wp-content\/uploads\/50-jahre-febu-stanzteile-kunststoffspritzguss.jpg","@id":"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/#mainImage","width":694,"height":162},"primaryImageOfPage":{"@id":"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/#mainImage"},"datePublished":"2015-02-02T17:01:15+01:00","dateModified":"2022-08-12T09:13:02+01:00"},{"@type":"WebSite","@id":"https:\/\/febu.de\/en\/#website","url":"https:\/\/febu.de\/en\/","name":"FEBU STANZ- & KUNSTSTOFFTECHNIK","inLanguage":"en-US","publisher":{"@id":"https:\/\/febu.de\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"FEBU PUNCHING &amp; PLASTIC TECHNOLOGY -","og:type":"article","og:title":"50 Jahre FEBU - FEBU PUNCHING &amp; PLASTIC TECHNOLOGY","og:description":"Am 02. Februar wurde FEBU 50 Jahre alt. Wir sind stolz, dass sich Qualit\u00e4t und Flexibilit\u00e4t durchgesetzt haben! Wir danken unseren Kunden, unseren Mitarbeitern sowie unseren Partnern f\u00fcr 50 spannende Jahre und freuen uns auf die weitere Zusammenarbeit mit Ihnen. Seit 1965 ist eine Menge passiert - machen Sie sich selbst ein Bild:","og:url":"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/","article:published_time":"2015-02-02T16:01:15+00:00","article:modified_time":"2022-08-12T08:13:02+00:00","twitter:card":"summary","twitter:title":"50 Jahre FEBU - FEBU PUNCHING &amp; PLASTIC TECHNOLOGY","twitter:description":"Am 02. Februar wurde FEBU 50 Jahre alt. Wir sind stolz, dass sich Qualit\u00e4t und Flexibilit\u00e4t durchgesetzt haben! Wir danken unseren Kunden, unseren Mitarbeitern sowie unseren Partnern f\u00fcr 50 spannende Jahre und freuen uns auf die weitere Zusammenarbeit mit Ihnen. Seit 1965 ist eine Menge passiert - machen Sie sich selbst ein Bild:"},"aioseo_meta_data":{"post_id":"808","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"},\"blockGraphs\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-08 15:11:53","updated":"2025-06-17 09:38:23","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/febu.de\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/febu.de\/category\/neuigkeiten\/\" title=\"News\">News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t50 Jahre FEBU\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/febu.de\/en\/"},{"label":"News","link":"https:\/\/febu.de\/category\/neuigkeiten\/"},{"label":"50 Jahre FEBU","link":"https:\/\/febu.de\/en\/2015\/02\/50-jahre-febu\/"}],"_links":{"self":[{"href":"https:\/\/febu.de\/en\/wp-json\/wp\/v2\/posts\/808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/febu.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/febu.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/febu.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/febu.de\/en\/wp-json\/wp\/v2\/comments?post=808"}],"version-history":[{"count":4,"href":"https:\/\/febu.de\/en\/wp-json\/wp\/v2\/posts\/808\/revisions"}],"predecessor-version":[{"id":2746,"href":"https:\/\/febu.de\/en\/wp-json\/wp\/v2\/posts\/808\/revisions\/2746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/febu.de\/en\/wp-json\/wp\/v2\/media\/819"}],"wp:attachment":[{"href":"https:\/\/febu.de\/en\/wp-json\/wp\/v2\/media?parent=808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/febu.de\/en\/wp-json\/wp\/v2\/categories?post=808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/febu.de\/en\/wp-json\/wp\/v2\/tags?post=808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}